{"id":40,"date":"2017-12-11T08:36:13","date_gmt":"2017-12-11T07:36:13","guid":{"rendered":"http:\/\/wuerzburger-fussballschule.de\/neu\/?p=40"},"modified":"2017-12-29T19:31:02","modified_gmt":"2017-12-29T18:31:02","slug":"dfb-inhalte","status":"publish","type":"post","link":"http:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/","title":{"rendered":"DFB Inhalte"},"content":{"rendered":"<p>Wir trainieren nach dem Konzept des DFB. Das bedeutet Fu\u00dfball auf h\u00f6chstem technischen Niveau sowie ein offensiv ausgerichtetes Spielsystem im h\u00f6chsten Spieltempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir trainieren nach dem Konzept des DFB. Das bedeutet Fu\u00dfball auf h\u00f6chstem technischen Niveau sowie ein offensiv ausgerichtetes Spielsystem im h\u00f6chsten Spieltempo.<\/p>\n","protected":false},"author":1,"featured_media":41,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-40","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vermittlung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DFB Inhalte - W\u00fcrzburger Fussballschule Michael Hochrein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DFB Inhalte - W\u00fcrzburger Fussballschule Michael Hochrein\" \/>\n<meta property=\"og:description\" content=\"Wir trainieren nach dem Konzept des DFB. Das bedeutet Fu\u00dfball auf h\u00f6chstem technischen Niveau sowie ein offensiv ausgerichtetes Spielsystem im h\u00f6chsten Spieltempo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/\" \/>\n<meta property=\"og:site_name\" content=\"W\u00fcrzburger Fussballschule Michael Hochrein\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-11T07:36:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-29T18:31:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wuerzburger-fussballschule.de\/neu\/wp-content\/uploads\/2017\/12\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"administrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"administrator\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/\"},\"author\":{\"name\":\"administrator\",\"@id\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/#\\\/schema\\\/person\\\/81546e32bdbcd3063360b0afed3fc502\"},\"headline\":\"DFB Inhalte\",\"datePublished\":\"2017-12-11T07:36:13+00:00\",\"dateModified\":\"2017-12-29T18:31:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/\"},\"wordCount\":27,\"publisher\":{\"@id\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png\",\"articleSection\":[\"Vermittlung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/\",\"url\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/\",\"name\":\"DFB Inhalte - W\u00fcrzburger Fussballschule Michael Hochrein\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png\",\"datePublished\":\"2017-12-11T07:36:13+00:00\",\"dateModified\":\"2017-12-29T18:31:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/#primaryimage\",\"url\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png\",\"contentUrl\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png\",\"width\":880,\"height\":660,\"caption\":\"DFB Logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/2017\\\/12\\\/11\\\/dfb-inhalte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DFB Inhalte\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/#website\",\"url\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/\",\"name\":\"W\u00fcrzburger Fussballschule Michael Hochrein\",\"description\":\"Die Fussballschule von Michael Hochrein\",\"publisher\":{\"@id\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/#organization\",\"name\":\"W\u00fcrzburger Fussballschule Michael Hochrein\",\"url\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo_wuerzburgerFussballschule_MichaelHochrein.png\",\"contentUrl\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo_wuerzburgerFussballschule_MichaelHochrein.png\",\"width\":512,\"height\":150,\"caption\":\"W\u00fcrzburger Fussballschule Michael Hochrein\"},\"image\":{\"@id\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/#\\\/schema\\\/person\\\/81546e32bdbcd3063360b0afed3fc502\",\"name\":\"administrator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/559e11ac0de2fb5781df1c45a8e3541f938e9ec116461d92ec100ae4953b1ea1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/559e11ac0de2fb5781df1c45a8e3541f938e9ec116461d92ec100ae4953b1ea1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/559e11ac0de2fb5781df1c45a8e3541f938e9ec116461d92ec100ae4953b1ea1?s=96&d=mm&r=g\",\"caption\":\"administrator\"},\"url\":\"http:\\\/\\\/wuerzburger-fussballschule.de\\\/neu\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DFB Inhalte - W\u00fcrzburger Fussballschule Michael Hochrein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/","og_locale":"de_DE","og_type":"article","og_title":"DFB Inhalte - W\u00fcrzburger Fussballschule Michael Hochrein","og_description":"Wir trainieren nach dem Konzept des DFB. Das bedeutet Fu\u00dfball auf h\u00f6chstem technischen Niveau sowie ein offensiv ausgerichtetes Spielsystem im h\u00f6chsten Spieltempo.","og_url":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/","og_site_name":"W\u00fcrzburger Fussballschule Michael Hochrein","article_published_time":"2017-12-11T07:36:13+00:00","article_modified_time":"2017-12-29T18:31:02+00:00","og_image":[{"width":880,"height":660,"url":"https:\/\/wuerzburger-fussballschule.de\/neu\/wp-content\/uploads\/2017\/12\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png","type":"image\/png"}],"author":"administrator","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"administrator"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/#article","isPartOf":{"@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/"},"author":{"name":"administrator","@id":"http:\/\/wuerzburger-fussballschule.de\/neu\/#\/schema\/person\/81546e32bdbcd3063360b0afed3fc502"},"headline":"DFB Inhalte","datePublished":"2017-12-11T07:36:13+00:00","dateModified":"2017-12-29T18:31:02+00:00","mainEntityOfPage":{"@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/"},"wordCount":27,"publisher":{"@id":"http:\/\/wuerzburger-fussballschule.de\/neu\/#organization"},"image":{"@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/#primaryimage"},"thumbnailUrl":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-content\/uploads\/2017\/12\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png","articleSection":["Vermittlung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/","url":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/","name":"DFB Inhalte - W\u00fcrzburger Fussballschule Michael Hochrein","isPartOf":{"@id":"http:\/\/wuerzburger-fussballschule.de\/neu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/#primaryimage"},"image":{"@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/#primaryimage"},"thumbnailUrl":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-content\/uploads\/2017\/12\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png","datePublished":"2017-12-11T07:36:13+00:00","dateModified":"2017-12-29T18:31:02+00:00","breadcrumb":{"@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/#primaryimage","url":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-content\/uploads\/2017\/12\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png","contentUrl":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-content\/uploads\/2017\/12\/wuFu_dfb_wuerzburgerFussballschule_MichaelHochrein.png","width":880,"height":660,"caption":"DFB Logo"},{"@type":"BreadcrumbList","@id":"https:\/\/wuerzburger-fussballschule.de\/neu\/2017\/12\/11\/dfb-inhalte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/wuerzburger-fussballschule.de\/neu\/"},{"@type":"ListItem","position":2,"name":"DFB Inhalte"}]},{"@type":"WebSite","@id":"http:\/\/wuerzburger-fussballschule.de\/neu\/#website","url":"http:\/\/wuerzburger-fussballschule.de\/neu\/","name":"W\u00fcrzburger Fussballschule Michael Hochrein","description":"Die Fussballschule von Michael Hochrein","publisher":{"@id":"http:\/\/wuerzburger-fussballschule.de\/neu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/wuerzburger-fussballschule.de\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"http:\/\/wuerzburger-fussballschule.de\/neu\/#organization","name":"W\u00fcrzburger Fussballschule Michael Hochrein","url":"http:\/\/wuerzburger-fussballschule.de\/neu\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/wuerzburger-fussballschule.de\/neu\/#\/schema\/logo\/image\/","url":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-content\/uploads\/2017\/12\/logo_wuerzburgerFussballschule_MichaelHochrein.png","contentUrl":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-content\/uploads\/2017\/12\/logo_wuerzburgerFussballschule_MichaelHochrein.png","width":512,"height":150,"caption":"W\u00fcrzburger Fussballschule Michael Hochrein"},"image":{"@id":"http:\/\/wuerzburger-fussballschule.de\/neu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/wuerzburger-fussballschule.de\/neu\/#\/schema\/person\/81546e32bdbcd3063360b0afed3fc502","name":"administrator","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/559e11ac0de2fb5781df1c45a8e3541f938e9ec116461d92ec100ae4953b1ea1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/559e11ac0de2fb5781df1c45a8e3541f938e9ec116461d92ec100ae4953b1ea1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/559e11ac0de2fb5781df1c45a8e3541f938e9ec116461d92ec100ae4953b1ea1?s=96&d=mm&r=g","caption":"administrator"},"url":"http:\/\/wuerzburger-fussballschule.de\/neu\/author\/administrator\/"}]}},"_links":{"self":[{"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/posts\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":1,"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/posts\/40\/revisions"}],"predecessor-version":[{"id":42,"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/posts\/40\/revisions\/42"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/media\/41"}],"wp:attachment":[{"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/categories?post=40"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wuerzburger-fussballschule.de\/neu\/wp-json\/wp\/v2\/tags?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}